{"id":2731,"date":"2021-01-29T11:30:43","date_gmt":"2021-01-29T17:30:43","guid":{"rendered":"http:\/\/nasodio.com\/home\/?page_id=2731"},"modified":"2021-03-29T18:52:57","modified_gmt":"2021-03-30T00:52:57","slug":"remedios-del-bosque-2021","status":"publish","type":"page","link":"https:\/\/nasodio.com\/home\/remedios-del-bosque-2021\/","title":{"rendered":"Remedios Del Bosque 2021"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/1&#8243;][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_column_text c_id=&#8221;.vc_1473786443468&#8243; el_class=&#8221;logocel&#8221;]<a href=\"http:\/\/nasodio.com\/home\/\"><img decoding=\"async\" class=\"alignnone wp-image-254 size-full\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2016\/08\/logosodio.png\" alt=\"logosodio\" width=\"335\" height=\"110\" \/><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-xs&#8221;][vc_column_text c_id=&#8221;.vc_1473786461502&#8243; el_class=&#8221;logo&#8221;]<a href=\"http:\/\/nasodio.com\/home\/\"><img decoding=\"async\" class=\"alignleft wp-image-34 size-full\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2016\/08\/logo.png\" alt=\"logo\" width=\"152\" height=\"49\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2016\/08\/logo.png 152w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2016\/08\/logo-150x49.png 150w\" sizes=\"(max-width: 152px) 100vw, 152px\" \/><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-xs&#8221;][vc_column_text c_id=&#8221;.vc_1473786370636&#8243; p_css=&#8221;font-family:Stan;color:#000000;&#8221; link_css=&#8221;color:#000000;&#8221; list_css=&#8221;font-family:Stan;color:#000000;font-size:20px;&#8221; el_class=&#8221;men&#8221;]<\/p>\n<ul>\n<li style=\"text-align: left;\"><a href=\"http:\/\/nasodio.com\/home\/Archive\"><span style=\"color: #000000;\">Archive<\/span><\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_column_text c_id=&#8221;.vc_1473786404024&#8243; p_css=&#8221;font-family:Stan;color:#000000;&#8221; link_css=&#8221;color:#000000;&#8221; list_css=&#8221;font-family:Stan;color:#000000;font-size:20px;&#8221; el_class=&#8221;menmov&#8221;]<\/p>\n<ul>\n<li style=\"text-align: left;\"><a href=\"http:\/\/nasodio.com\/home\/Archive\"><span style=\"color: #000000;\">Archive<\/span><\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner p_top=&#8221;0&#8243; p_bottom=&#8221;0&#8243; m_top=&#8221;0&#8243; m_bottom=&#8221;0&#8243;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243; css=&#8221;.vc_custom_1509658029675{margin-bottom: 45px !important;}&#8221;][vc_single_image source=&#8221;media_library&#8221; image=&#8221;2743&#8243; alignment=&#8221;center&#8221; img_size=&#8221;full&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943438793&#8243;]<img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2753\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14.jpg\" alt=\"Remedios_14\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_14-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943456912&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2754\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15.jpg\" alt=\"Remedios_15\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_15-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611943518083&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2746\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07.jpg\" alt=\"Remedios_07\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_07-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243; offset=&#8221;vc_col-xs-12 vc_hidden-xs&#8221;][vc_column_text c_id=&#8221;.vc_1614102081122&#8243;]<span style=\"color: #000000; font-family: stanb;\">Remedios del Bosque<\/span><br \/>\n<span style=\"color: #000000; font-family: stan;\">Documentaci\u00f3n &amp; Mantenimiento de Marca<\/span><\/p>\n<p style=\"line-height: 16pt; text-align: left;\"><span style=\"color: #000000; font-family: stan; font-size: 9pt;\">Ubicaci\u00f3n:\u00a0M\u00e9xico<br \/>\nDocumentaci\u00f3n &amp; Dise\u00f1o: SODIO<br \/>\nRe-branding, Dise\u00f1o de Aplicaciones y Dise\u00f1o Web<br \/>\nConoce m\u00e1s sobre REMEDIOS DEL BOSQUE en <a style=\"color: #000000;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=9408433ec9&amp;e=ab0335c28a\" target=\"_blank\">@remediosdelbosque<\/a>\u00a0y en <a style=\"color: #000000;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=84ade075c8&amp;e=ab0335c28a\" target=\"_blank\">www.remediosdelbosque.com<\/a><br \/>\n<\/span><\/p>\n<p style=\"line-height: 16pt; text-align: left;\"><span style=\"color: #cccccc; font-family: atl; font-size: 9pt;\">Location: M\u00e9xico<br \/>\nDocumentation &amp; Design: SODIO<br \/>\nRe-branding, Collateral&#8217;s Design and Web Design<br \/>\nLearn more about REMEDIOS DEL BOSQUE in\u00a0<a style=\"color: #cccccc;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=9408433ec9&amp;e=ab0335c28a\" target=\"_blank\">@remediosdelbosque<\/a>\u00a0and in\u00a0<a style=\"color: #cccccc;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=84ade075c8&amp;e=ab0335c28a\" target=\"_blank\">www.remediosdelbosque.com<\/a><br \/>\n<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; offset=&#8221;vc_col-xs-4 vc_hidden-xs&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611947708474&#8243; h5_css=&#8221;font-family:stanb;color:#000000;&#8221; p_css=&#8221;font-family:Stan;&#8221;]<span style=\"color: #000000; font-family: stanb;\">Remedios del Bosque<\/span><br \/>\n<span style=\"color: #000000; font-family: stan;\">Documentaci\u00f3n &amp; Mantenimiento de Marca<\/span><\/p>\n<p style=\"line-height: 16pt; text-align: left;\"><span style=\"color: #000000; font-family: stan; font-size: 10pt;\">Ubicaci\u00f3n: M\u00e9xico<br \/>\nDocumentaci\u00f3n &amp; Dise\u00f1o: SODIO<br \/>\nRe-branding, Dise\u00f1o de Aplicaciones y Dise\u00f1o Web<br \/>\n<span class=\"\">Conoce m\u00e1s sobre REMEDIOS DEL BOSQUE en\u00a0<a style=\"color: #000000;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=9408433ec9&amp;e=ab0335c28a\" target=\"_blank\">@remediosdelbosque<\/a>\u00a0y en\u00a0<a style=\"color: #000000;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=84ade075c8&amp;e=ab0335c28a\" target=\"_blank\">www.remediosdelbosque.com<\/a><\/span><br \/>\n<\/span><\/p>\n<p style=\"line-height: 16pt; text-align: left;\"><span style=\"color: #cccccc; font-family: atl; font-size: 10pt;\">Location: M\u00e9xico<br \/>\nDocumentation &amp; Design: SODIO<br \/>\nRe-branding, Collateral&#8217;s Design and Web Design<br \/>\nLearn more about REMEDIOS DEL BOSQUE in\u00a0<a style=\"color: #cccccc;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=9408433ec9&amp;e=ab0335c28a\" target=\"_blank\">@remediosdelbosque<\/a>\u00a0and in\u00a0<a style=\"color: #cccccc;\" href=\"https:\/\/nasodio.us17.list-manage.com\/track\/click?u=bb029c273e5a6844d6675ae5a&amp;id=84ade075c8&amp;e=ab0335c28a\" target=\"_blank\">www.remediosdelbosque.com<\/a><br \/>\n<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943558235&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2748\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09.jpg\" alt=\"Remedios_09\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_09-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943597247&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2742\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03.jpg\" alt=\"Remedios_03\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_03-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611945757605&#8243;]<\/p>\n<div style=\"width: 800px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-2731-1\" width=\"800\" height=\"450\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Valores_Sub.mp4?_=1\" \/><a href=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Valores_Sub.mp4\">http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Valores_Sub.mp4<\/a><\/video><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946196427&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2750\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11.jpg\" alt=\"Remedios_11\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_11-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946212518&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2749\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10.jpg\" alt=\"Remedios_10\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_10-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946331071&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2745\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06.jpg\" alt=\"Remedios_06\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_06-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946435784&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2771 size-full\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Re_01.gif\" alt=\"Re_01\" width=\"600\" height=\"600\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946460076&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2772\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Re_02.gif\" alt=\"Re_02\" width=\"600\" height=\"600\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946645247&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2735\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1.jpg\" alt=\"Acomodo-Web-REMEDIOS_1\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_1-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946532509&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2741\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02.jpg\" alt=\"Remedios_02\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_02-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946667145&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2736\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web.jpg\" alt=\"Acomodo-Web-REMEDIOS_2_web\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_2_web-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611946689822&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2751\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12.jpg\" alt=\"Remedios_12\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_12-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946722942&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2739\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web.jpg\" alt=\"Acomodo-Web-REMEDIOS_5_web\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_5_web-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946772982&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2752\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13.jpg\" alt=\"Remedios_13\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_13-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946816447&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2738\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web.jpg\" alt=\"Acomodo-Web-REMEDIOS_4_web\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_4_web-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611946853102&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2737\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web.jpg\" alt=\"Acomodo-Web-REMEDIOS_3_web\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Acomodo-Web-REMEDIOS_3_web-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611947053694&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2747\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08.jpg\" alt=\"Remedios_08\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_08-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text c_id=&#8221;.vc_1611947111883&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2740\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01.jpg\" alt=\"Remedios_01\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01.jpg 1920w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-480x320.jpg 480w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-768x512.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-1200x800.jpg 1200w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-405x270.jpg 405w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-780x520.jpg 780w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-659x439.jpg 659w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-1013x675.jpg 1013w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_01-880x587.jpg 880w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611947157629&#8243;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2744\" src=\"http:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05.jpg\" alt=\"Remedios_05\" width=\"1280\" height=\"1920\" srcset=\"https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05.jpg 1280w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-320x480.jpg 320w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-768x1152.jpg 768w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-800x1200.jpg 800w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-180x270.jpg 180w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-520x780.jpg 520w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-293x439.jpg 293w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-450x675.jpg 450w, https:\/\/nasodio.com\/home\/wp-content\/uploads\/2021\/01\/Remedios_05-587x880.jpg 587w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1614101123792&#8243; link_css=&#8221;font-family:Atl;font-size:16px;&#8221;]<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/nasodio.com\/home\/xolo-music\/\"><span style=\"color: #cccccc;\">Xolo Music<\/span><\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611941536833&#8243; link_css=&#8221;font-family:Atl;font-size:16px;&#8221;]<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/nasodio.com\/home\/persona-on-paper\/\"><span style=\"color: #cccccc;\">PERSONA on paper<\/span><\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/1&#8243;][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_column_text c_id=&#8221;.vc_1473786443468&#8243; el_class=&#8221;logocel&#8221;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-xs&#8221;][vc_column_text c_id=&#8221;.vc_1473786461502&#8243; el_class=&#8221;logo&#8221;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-xs&#8221;][vc_column_text c_id=&#8221;.vc_1473786370636&#8243; p_css=&#8221;font-family:Stan;color:#000000;&#8221; link_css=&#8221;color:#000000;&#8221; list_css=&#8221;font-family:Stan;color:#000000;font-size:20px;&#8221; el_class=&#8221;men&#8221;] Archive [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;fixed&#8221;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_column_text c_id=&#8221;.vc_1473786404024&#8243; p_css=&#8221;font-family:Stan;color:#000000;&#8221; link_css=&#8221;color:#000000;&#8221; list_css=&#8221;font-family:Stan;color:#000000;font-size:20px;&#8221; el_class=&#8221;menmov&#8221;] Archive [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner p_top=&#8221;0&#8243; p_bottom=&#8221;0&#8243; m_top=&#8221;0&#8243; m_bottom=&#8221;0&#8243;][vc_column_inner width=&#8221;1\/1&#8243; offset=&#8221;vc_col-xs-12&#8243; css=&#8221;.vc_custom_1509658029675{margin-bottom: 45px !important;}&#8221;][vc_single_image source=&#8221;media_library&#8221; image=&#8221;2743&#8243; alignment=&#8221;center&#8221; img_size=&#8221;full&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943438793&#8243;][\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text c_id=&#8221;.vc_1611943456912&#8243;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2731","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/pages\/2731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/comments?post=2731"}],"version-history":[{"count":22,"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/pages\/2731\/revisions"}],"predecessor-version":[{"id":2836,"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/pages\/2731\/revisions\/2836"}],"wp:attachment":[{"href":"https:\/\/nasodio.com\/home\/wp-json\/wp\/v2\/media?parent=2731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}